{"id":4439,"date":"2021-10-12T16:27:24","date_gmt":"2021-10-12T16:27:24","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart2\/elementor\/?page_id=4439"},"modified":"2026-03-31T00:59:58","modified_gmt":"2026-03-31T00:59:58","slug":"contact","status":"publish","type":"page","link":"https:\/\/akhammal.com\/tr\/contact\/","title":{"rendered":"\u0130leti\u015fim"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4439\" class=\"elementor elementor-4439\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-cb322d0 e-flex e-con-boxed e-con e-parent\" data-id=\"cb322d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-789122a e-con-full e-flex e-con e-child\" data-id=\"789122a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-775ddc4 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"775ddc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Bize ula\u015f\u0131n<br \/>\n<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c67846 wd-cf7 elementor-widget elementor-widget-wd_contact_form_7\" data-id=\"3c67846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1572-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1572\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tr\/wp-json\/wp\/v2\/pages\/4439#wpcf7-f1572-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/tr\/wp-json\/wp\/v2\/pages\/4439#wpcf7-f1572-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1572\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1572-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wd-grid-g\">\n\t<div class=\"wd-grid-f-stretch\">\n\t\t<div class=\"wd-col\">\n\t\t\t<p><label>Sizin ad\u0131n\u0131z<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"wd-col\">\n\t\t\t<p><label>E-posta adresiniz<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wd-grid-f-stretch\">\n\t\t<div class=\"wd-col\">\n\t\t\t<p><label>Telefon numaras\u0131<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-767\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-767\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"wd-col\">\n\t\t\t<p><label>\u015eirket<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-1\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div>\n\t\t<p><label>Mesaj\u0131n\u0131z<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-color-black\" type=\"submit\" value=\"B\u0130R SORU SORUN\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"tr\"\/><\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Neem contact met ons op Uw naam Uw e-mailadres Telefoonnummer Bedrijf Uw bericht<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4439","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/akhammal.com\/tr\/wp-json\/wp\/v2\/pages\/4439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/akhammal.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/akhammal.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/akhammal.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/akhammal.com\/tr\/wp-json\/wp\/v2\/comments?post=4439"}],"version-history":[{"count":16,"href":"https:\/\/akhammal.com\/tr\/wp-json\/wp\/v2\/pages\/4439\/revisions"}],"predecessor-version":[{"id":30031,"href":"https:\/\/akhammal.com\/tr\/wp-json\/wp\/v2\/pages\/4439\/revisions\/30031"}],"wp:attachment":[{"href":"https:\/\/akhammal.com\/tr\/wp-json\/wp\/v2\/media?parent=4439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}